{"id":30697,"date":"2026-07-10T09:22:25","date_gmt":"2026-07-10T07:22:25","guid":{"rendered":"https:\/\/puntdereferencia.org\/?p=30697"},"modified":"2026-07-10T09:29:20","modified_gmt":"2026-07-10T07:29:20","slug":"mamadou-y-carmen-cuando-una-mentoria-se-convierte-en-amistad","status":"publish","type":"post","link":"https:\/\/puntdereferencia.org\/es\/mamadou-y-carmen-cuando-una-mentoria-se-convierte-en-amistad\/","title":{"rendered":"Mamadou y Carmen: cuando una mentor\u00eda se convierte en amistad"},"content":{"rendered":"<p class=\"isSelectedEnd\">Hoy hemos quedado Mamadou Tela Diallo y su antigua mentora, Carmen Tur\u00e9gano, para comer. Hemos estado con su mujer y su hijo de cuatro meses.<\/p>\n<p class=\"isSelectedEnd\">Hace cinco a\u00f1os que Mamadou lleg\u00f3 a Barcelona. Encontr\u00f3 una asociaci\u00f3n llamada MPDL, en Badalona, y all\u00ed lo orientaron hacia Punt de Refer\u00e8ncia, nuestra entidad. En aquel momento, Mamadou estudiaba castellano d\u00eda y noche: en l\u00ednea, en la escuela, en la calle, con las nuevas personas que iba conociendo&#8230; Todo para aprender m\u00e1s r\u00e1pido. Cuando lleg\u00f3 a Punt de Refer\u00e8ncia, tambi\u00e9n entr\u00f3 en contacto con el catal\u00e1n.<\/p>\n<p class=\"isSelectedEnd\">En la primera acogida en la entidad habl\u00f3 con la t\u00e9cnica Alicia, que le recomend\u00f3 una mentora para acompa\u00f1arlo en su llegada. Mamadou no quer\u00eda cambiar de referente, pero Alicia nos present\u00f3 para que yo fuera su mentora. Y aqu\u00ed estamos, Mamadou y Carmen, cuatro a\u00f1os despu\u00e9s. Porque, efectivamente, la mentor\u00eda se llev\u00f3 a cabo y dio lugar a un v\u00ednculo de confianza muy s\u00f3lido.<\/p>\n<p class=\"isSelectedEnd\">En un principio, desde Punt de Refer\u00e8ncia nos propusieron una mentor\u00eda de ocho meses, con un encuentro semanal en un espacio p\u00fablico. Cuando aceptamos por escrito las condiciones, elaboramos nuestro plan de trabajo.<\/p>\n<p class=\"isSelectedEnd\">\u2014Aquel plan de trabajo ten\u00eda muchas cosas \u2014dice Mamadou\u2014. Ahora conozco los museos y todos los lugares para visitar: el Camp Nou, el Tibidabo, la Sagrada Familia, el Park G\u00fcell&#8230; Lo conozco todo.<\/p>\n<p class=\"isSelectedEnd\">El plan de trabajo compartido ten\u00eda como objetivo acompa\u00f1ar a Mamadou en las decisiones que deb\u00eda tomar ante nuevas situaciones. Aspectos como el aprendizaje de las lenguas, las visitas a la ciudad o la cultura eran el medio para ir abordando sus dudas y tambi\u00e9n sus preocupaciones. Mamadou ten\u00eda que tomar decisiones importantes: la b\u00fasqueda de trabajo, la revisi\u00f3n de situaciones dif\u00edciles o la respuesta a muchas preguntas. Pasaron unos cuatro meses y el reto m\u00e1s complicado fue encontrar su primera vivienda.<\/p>\n<p class=\"isSelectedEnd\">Barcelona atravesaba uno de los peores momentos de especulaci\u00f3n inmobiliaria. Hab\u00eda decenas de ofertas de habitaciones en las plataformas, pero ninguna parec\u00eda estar realmente disponible. Consensuamos un m\u00e9todo para que Mamadou hiciera la b\u00fasqueda y estableciera contactos. El resultado fue infructuoso.<\/p>\n<p class=\"isSelectedEnd\">\u2014Nada de nada \u2014dice Mamadou\u2014. Nunca te llaman.<\/p>\n<p class=\"isSelectedEnd\">Un d\u00eda nos sentamos en el Paral\u00b7lel y cada uno cogi\u00f3 su tel\u00e9fono para llamar una y otra vez. Hasta que apareci\u00f3 Pedro, un hombre mayor que acept\u00f3 con mucho gusto alquilarle una habitaci\u00f3n. All\u00ed vivi\u00f3 Mamadou hasta que lleg\u00f3 el cambio m\u00e1s importante de su vida.<\/p>\n<p class=\"isSelectedEnd\">Recordamos que, el d\u00eda de su 24.\u00ba cumplea\u00f1os, en casa de Pedro, nos reunimos con sus compa\u00f1eras de trabajo. Yo, en aquel momento, todav\u00eda era su mentora y me alegr\u00f3 ver a Pedro compartiendo aquel momento con todos nosotros. Tambi\u00e9n estuvo presente en su boda.<\/p>\n<p class=\"isSelectedEnd\">La mentor\u00eda finaliz\u00f3 en el plazo previsto, pero acordamos seguir manteniendo el contacto porque hab\u00eda surgido una buena relaci\u00f3n. Y, desde entonces, hemos construido una buena amistad.<\/p>\n<p class=\"isSelectedEnd\">A finales de ese mismo a\u00f1o, Mamadou me llam\u00f3 para decirme que ten\u00eda una buena noticia. Nos encontramos en los jardines de la Torre Gl\u00f2ries. La noticia era realmente importante: se hab\u00eda comprometido con una chica de Granollers.<\/p>\n<p class=\"isSelectedEnd\">\u2014Me he comprometido, Carmen, y cuando tengamos piso nos casaremos primero por lo civil. Despu\u00e9s celebraremos la boda y queremos que vengas.<\/p>\n<p class=\"isSelectedEnd\">Pero surgi\u00f3 una nueva dificultad en su proyecto de vida: encontrar un piso de alquiler. Aunque tanto Mamadou como su prometida ten\u00edan contrato de trabajo, parec\u00eda que nadie quer\u00eda alquilarles una vivienda. Cuando me pidi\u00f3 ayuda, fuimos personalmente a Ripollet, Cerdanyola y Montcada. Nada de nada. Finalmente, encontr\u00f3 un piso muy adecuado en Granollers, en un barrio bien comunicado, con todos los servicios p\u00fablicos y cerca de la familia de su mujer.<\/p>\n<p class=\"isSelectedEnd\">No pude asistir a la boda, pero vi las fotograf\u00edas, llenas de color y de m\u00fasica.<\/p>\n<p class=\"isSelectedEnd\">Hoy, en 2026, han venido a darme el p\u00e9same por el fallecimiento de mi padre, un hombre de 99 a\u00f1os a quien Mamadou respetaba mucho. Han tenido un beb\u00e9, un ni\u00f1o despierto, que aprender\u00e1, igual que sus primos, catal\u00e1n y castellano. Por supuesto, Baba y Nene hablan con su hijo en pulaar y en franc\u00e9s. Y este precioso beb\u00e9 tambi\u00e9n aprender\u00e1 otros idiomas, por si alg\u00fan d\u00eda quiere viajar a pa\u00edses lejanos.<\/p>\n<p class=\"isSelectedEnd\">Mamadou cambi\u00f3 de trabajo hace medio a\u00f1o. No siempre es f\u00e1cil encontrar un buen empleo cerca de casa. Ahora viaja cada d\u00eda laborable de Granollers a Barcelona, pero ya est\u00e1 buscando, sin prisa, un trabajo en su ciudad.<\/p>\n<p class=\"isSelectedEnd\">Y si la vida es una sucesi\u00f3n de nuevos retos, ambos estamos de acuerdo en que la mentor\u00eda para j\u00f3venes de Punt de Refer\u00e8ncia es una herramienta de ayuda muy eficaz. Tener una persona de referencia para el crecimiento personal puede ayudar a comprender la sociedad en la que vivimos y nuestro lugar en ella.<\/p>\n<p><strong>Mamadou Tela Diallo y Carmen Tur\u00e9gano<\/strong><br \/>\n17 de junio de 2026<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hoy hemos quedado Mamadou Tela Diallo y su antigua mentora, Carmen Tur\u00e9gano, para comer. Hemos estado con su mujer y su hijo de cuatro meses. Hace cinco a\u00f1os que Mamadou lleg\u00f3 a Barcelona. Encontr\u00f3 una asociaci\u00f3n llamada MPDL, en Badalona, y all\u00ed lo orientaron hacia Punt de Refer\u00e8ncia, nuestra entidad. En aquel momento, Mamadou estudiaba [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":30691,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[914],"tags":[],"class_list":["post-30697","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-opinion"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mamadou y Carmen: cuando una mentor\u00eda se convierte en amistad - Punt de Referencia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/puntdereferencia.org\/es\/mamadou-y-carmen-cuando-una-mentoria-se-convierte-en-amistad\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mamadou y Carmen: cuando una mentor\u00eda se convierte en amistad - Punt de Referencia\" \/>\n<meta property=\"og:description\" content=\"Hoy hemos quedado Mamadou Tela Diallo y su antigua mentora, Carmen Tur\u00e9gano, para comer. Hemos estado con su mujer y su hijo de cuatro meses. Hace cinco a\u00f1os que Mamadou lleg\u00f3 a Barcelona. Encontr\u00f3 una asociaci\u00f3n llamada MPDL, en Badalona, y all\u00ed lo orientaron hacia Punt de Refer\u00e8ncia, nuestra entidad. En aquel momento, Mamadou estudiaba [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/puntdereferencia.org\/es\/mamadou-y-carmen-cuando-una-mentoria-se-convierte-en-amistad\/\" \/>\n<meta property=\"og:site_name\" content=\"Punt de Referencia\" \/>\n<meta property=\"article:published_time\" content=\"2026-07-10T07:22:25+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-10T07:29:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/puntdereferencia.org\/wp-content\/uploads\/2026\/07\/a9035763-bd81-4dc3-aba3-b663f207f494-e1783668217761.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"1600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/puntdereferencia.org\/es\/mamadou-y-carmen-cuando-una-mentoria-se-convierte-en-amistad\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/puntdereferencia.org\/es\/mamadou-y-carmen-cuando-una-mentoria-se-convierte-en-amistad\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\/\/puntdereferencia.org\/es\/#\/schema\/person\/c475209bcc857303ec6ed0259d3cf078\"},\"headline\":\"Mamadou y Carmen: cuando una mentor\u00eda se convierte en amistad\",\"datePublished\":\"2026-07-10T07:22:25+00:00\",\"dateModified\":\"2026-07-10T07:29:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/puntdereferencia.org\/es\/mamadou-y-carmen-cuando-una-mentoria-se-convierte-en-amistad\/\"},\"wordCount\":882,\"image\":{\"@id\":\"https:\/\/puntdereferencia.org\/es\/mamadou-y-carmen-cuando-una-mentoria-se-convierte-en-amistad\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/puntdereferencia.org\/wp-content\/uploads\/2026\/07\/a9035763-bd81-4dc3-aba3-b663f207f494-e1783668217761.jpeg\",\"articleSection\":[\"OPINI\u00d3N\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/puntdereferencia.org\/es\/mamadou-y-carmen-cuando-una-mentoria-se-convierte-en-amistad\/\",\"url\":\"https:\/\/puntdereferencia.org\/es\/mamadou-y-carmen-cuando-una-mentoria-se-convierte-en-amistad\/\",\"name\":\"Mamadou y Carmen: cuando una mentor\u00eda se convierte en amistad - Punt de Referencia\",\"isPartOf\":{\"@id\":\"https:\/\/puntdereferencia.org\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/puntdereferencia.org\/es\/mamadou-y-carmen-cuando-una-mentoria-se-convierte-en-amistad\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/puntdereferencia.org\/es\/mamadou-y-carmen-cuando-una-mentoria-se-convierte-en-amistad\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/puntdereferencia.org\/wp-content\/uploads\/2026\/07\/a9035763-bd81-4dc3-aba3-b663f207f494-e1783668217761.jpeg\",\"datePublished\":\"2026-07-10T07:22:25+00:00\",\"dateModified\":\"2026-07-10T07:29:20+00:00\",\"author\":{\"@id\":\"https:\/\/puntdereferencia.org\/es\/#\/schema\/person\/c475209bcc857303ec6ed0259d3cf078\"},\"breadcrumb\":{\"@id\":\"https:\/\/puntdereferencia.org\/es\/mamadou-y-carmen-cuando-una-mentoria-se-convierte-en-amistad\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/puntdereferencia.org\/es\/mamadou-y-carmen-cuando-una-mentoria-se-convierte-en-amistad\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/puntdereferencia.org\/es\/mamadou-y-carmen-cuando-una-mentoria-se-convierte-en-amistad\/#primaryimage\",\"url\":\"https:\/\/puntdereferencia.org\/wp-content\/uploads\/2026\/07\/a9035763-bd81-4dc3-aba3-b663f207f494-e1783668217761.jpeg\",\"contentUrl\":\"https:\/\/puntdereferencia.org\/wp-content\/uploads\/2026\/07\/a9035763-bd81-4dc3-aba3-b663f207f494-e1783668217761.jpeg\",\"width\":1200,\"height\":1600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/puntdereferencia.org\/es\/mamadou-y-carmen-cuando-una-mentoria-se-convierte-en-amistad\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\/\/puntdereferencia.org\/es\/inicio\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mamadou y Carmen: cuando una mentor\u00eda se convierte en amistad\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/puntdereferencia.org\/es\/#website\",\"url\":\"https:\/\/puntdereferencia.org\/es\/\",\"name\":\"Punt de Referencia\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/puntdereferencia.org\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/puntdereferencia.org\/es\/#\/schema\/person\/c475209bcc857303ec6ed0259d3cf078\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/puntdereferencia.org\/es\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/ff306d55f6aedb51a29e838506fafaa76a30bce9f5db9aca2e28921b903aaad2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/ff306d55f6aedb51a29e838506fafaa76a30bce9f5db9aca2e28921b903aaad2?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"http:\/\/\/home\/puntref\/webapps\/web2024\"],\"url\":\"https:\/\/puntdereferencia.org\/es\/author\/admin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mamadou y Carmen: cuando una mentor\u00eda se convierte en amistad - Punt de Referencia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/puntdereferencia.org\/es\/mamadou-y-carmen-cuando-una-mentoria-se-convierte-en-amistad\/","og_locale":"es_ES","og_type":"article","og_title":"Mamadou y Carmen: cuando una mentor\u00eda se convierte en amistad - Punt de Referencia","og_description":"Hoy hemos quedado Mamadou Tela Diallo y su antigua mentora, Carmen Tur\u00e9gano, para comer. Hemos estado con su mujer y su hijo de cuatro meses. Hace cinco a\u00f1os que Mamadou lleg\u00f3 a Barcelona. Encontr\u00f3 una asociaci\u00f3n llamada MPDL, en Badalona, y all\u00ed lo orientaron hacia Punt de Refer\u00e8ncia, nuestra entidad. En aquel momento, Mamadou estudiaba [&hellip;]","og_url":"https:\/\/puntdereferencia.org\/es\/mamadou-y-carmen-cuando-una-mentoria-se-convierte-en-amistad\/","og_site_name":"Punt de Referencia","article_published_time":"2026-07-10T07:22:25+00:00","article_modified_time":"2026-07-10T07:29:20+00:00","og_image":[{"width":1200,"height":1600,"url":"https:\/\/puntdereferencia.org\/wp-content\/uploads\/2026\/07\/a9035763-bd81-4dc3-aba3-b663f207f494-e1783668217761.jpeg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/puntdereferencia.org\/es\/mamadou-y-carmen-cuando-una-mentoria-se-convierte-en-amistad\/#article","isPartOf":{"@id":"https:\/\/puntdereferencia.org\/es\/mamadou-y-carmen-cuando-una-mentoria-se-convierte-en-amistad\/"},"author":{"name":"admin","@id":"https:\/\/puntdereferencia.org\/es\/#\/schema\/person\/c475209bcc857303ec6ed0259d3cf078"},"headline":"Mamadou y Carmen: cuando una mentor\u00eda se convierte en amistad","datePublished":"2026-07-10T07:22:25+00:00","dateModified":"2026-07-10T07:29:20+00:00","mainEntityOfPage":{"@id":"https:\/\/puntdereferencia.org\/es\/mamadou-y-carmen-cuando-una-mentoria-se-convierte-en-amistad\/"},"wordCount":882,"image":{"@id":"https:\/\/puntdereferencia.org\/es\/mamadou-y-carmen-cuando-una-mentoria-se-convierte-en-amistad\/#primaryimage"},"thumbnailUrl":"https:\/\/puntdereferencia.org\/wp-content\/uploads\/2026\/07\/a9035763-bd81-4dc3-aba3-b663f207f494-e1783668217761.jpeg","articleSection":["OPINI\u00d3N"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/puntdereferencia.org\/es\/mamadou-y-carmen-cuando-una-mentoria-se-convierte-en-amistad\/","url":"https:\/\/puntdereferencia.org\/es\/mamadou-y-carmen-cuando-una-mentoria-se-convierte-en-amistad\/","name":"Mamadou y Carmen: cuando una mentor\u00eda se convierte en amistad - Punt de Referencia","isPartOf":{"@id":"https:\/\/puntdereferencia.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/puntdereferencia.org\/es\/mamadou-y-carmen-cuando-una-mentoria-se-convierte-en-amistad\/#primaryimage"},"image":{"@id":"https:\/\/puntdereferencia.org\/es\/mamadou-y-carmen-cuando-una-mentoria-se-convierte-en-amistad\/#primaryimage"},"thumbnailUrl":"https:\/\/puntdereferencia.org\/wp-content\/uploads\/2026\/07\/a9035763-bd81-4dc3-aba3-b663f207f494-e1783668217761.jpeg","datePublished":"2026-07-10T07:22:25+00:00","dateModified":"2026-07-10T07:29:20+00:00","author":{"@id":"https:\/\/puntdereferencia.org\/es\/#\/schema\/person\/c475209bcc857303ec6ed0259d3cf078"},"breadcrumb":{"@id":"https:\/\/puntdereferencia.org\/es\/mamadou-y-carmen-cuando-una-mentoria-se-convierte-en-amistad\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/puntdereferencia.org\/es\/mamadou-y-carmen-cuando-una-mentoria-se-convierte-en-amistad\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/puntdereferencia.org\/es\/mamadou-y-carmen-cuando-una-mentoria-se-convierte-en-amistad\/#primaryimage","url":"https:\/\/puntdereferencia.org\/wp-content\/uploads\/2026\/07\/a9035763-bd81-4dc3-aba3-b663f207f494-e1783668217761.jpeg","contentUrl":"https:\/\/puntdereferencia.org\/wp-content\/uploads\/2026\/07\/a9035763-bd81-4dc3-aba3-b663f207f494-e1783668217761.jpeg","width":1200,"height":1600},{"@type":"BreadcrumbList","@id":"https:\/\/puntdereferencia.org\/es\/mamadou-y-carmen-cuando-una-mentoria-se-convierte-en-amistad\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/puntdereferencia.org\/es\/inicio\/"},{"@type":"ListItem","position":2,"name":"Mamadou y Carmen: cuando una mentor\u00eda se convierte en amistad"}]},{"@type":"WebSite","@id":"https:\/\/puntdereferencia.org\/es\/#website","url":"https:\/\/puntdereferencia.org\/es\/","name":"Punt de Referencia","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/puntdereferencia.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/puntdereferencia.org\/es\/#\/schema\/person\/c475209bcc857303ec6ed0259d3cf078","name":"admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/puntdereferencia.org\/es\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/ff306d55f6aedb51a29e838506fafaa76a30bce9f5db9aca2e28921b903aaad2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ff306d55f6aedb51a29e838506fafaa76a30bce9f5db9aca2e28921b903aaad2?s=96&d=mm&r=g","caption":"admin"},"sameAs":["http:\/\/\/home\/puntref\/webapps\/web2024"],"url":"https:\/\/puntdereferencia.org\/es\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/puntdereferencia.org\/es\/wp-json\/wp\/v2\/posts\/30697","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/puntdereferencia.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/puntdereferencia.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/puntdereferencia.org\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/puntdereferencia.org\/es\/wp-json\/wp\/v2\/comments?post=30697"}],"version-history":[{"count":3,"href":"https:\/\/puntdereferencia.org\/es\/wp-json\/wp\/v2\/posts\/30697\/revisions"}],"predecessor-version":[{"id":30703,"href":"https:\/\/puntdereferencia.org\/es\/wp-json\/wp\/v2\/posts\/30697\/revisions\/30703"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/puntdereferencia.org\/es\/wp-json\/wp\/v2\/media\/30691"}],"wp:attachment":[{"href":"https:\/\/puntdereferencia.org\/es\/wp-json\/wp\/v2\/media?parent=30697"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/puntdereferencia.org\/es\/wp-json\/wp\/v2\/categories?post=30697"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/puntdereferencia.org\/es\/wp-json\/wp\/v2\/tags?post=30697"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}